{"id":210,"count":1,"description":"","link":"https:\/\/vanessariley.com\/blog\/tag\/mary-moore\/","name":"Mary Moore","slug":"mary-moore","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/vanessariley.com\/blog\/tag\/mary-moore\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/210\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vanessariley.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/tag\\\/mary-moore\\\/#listItem\",\"name\":\"Mary Moore\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/tag\\\/mary-moore\\\/#listItem\",\"position\":2,\"name\":\"Mary Moore\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/210\\\/#collectionpage\",\"url\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/210\\\/\",\"name\":\"Mary Moore - Vanessa Riley's Research and Shopping Blog\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/210\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/#organization\",\"name\":\"Vanessa Riley's Regency Reflections\",\"description\":\"Research, Resources, & Book Store\",\"url\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VanessaRileyAuthor\",\"https:\\\/\\\/www.instagram.com\\\/vanessarileyauthor\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@vanessarileyauthor\",\"https:\\\/\\\/www.youtube.com\\\/@FictionSagaQueen\",\"https:\\\/\\\/bsky.app\\\/profile\\\/vanessariley.bsky.social\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/\",\"name\":\"Vanessa Riley's Regency Reflections\",\"description\":\"Research, Resources, & Book Store\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/vanessariley.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mary Moore - Vanessa Riley's Research and Shopping Blog","description":"","canonical_url":"https:\/\/vanessariley.com\/blog\/tag\/mary-moore\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/tags\/210\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/vanessariley.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/vanessariley.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/vanessariley.com\/blog\/tag\/mary-moore\/#listItem","name":"Mary Moore"}},{"@type":"ListItem","@id":"https:\/\/vanessariley.com\/blog\/tag\/mary-moore\/#listItem","position":2,"name":"Mary Moore","previousItem":{"@type":"ListItem","@id":"https:\/\/vanessariley.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/tags\/210\/#collectionpage","url":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/tags\/210\/","name":"Mary Moore - Vanessa Riley's Research and Shopping Blog","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/vanessariley.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/tags\/210\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/vanessariley.com\/blog\/#organization","name":"Vanessa Riley's Regency Reflections","description":"Research, Resources, & Book Store","url":"https:\/\/vanessariley.com\/blog\/","sameAs":["https:\/\/www.facebook.com\/VanessaRileyAuthor","https:\/\/www.instagram.com\/vanessarileyauthor\/","https:\/\/www.tiktok.com\/@vanessarileyauthor","https:\/\/www.youtube.com\/@FictionSagaQueen","https:\/\/bsky.app\/profile\/vanessariley.bsky.social"]},{"@type":"WebSite","@id":"https:\/\/vanessariley.com\/blog\/#website","url":"https:\/\/vanessariley.com\/blog\/","name":"Vanessa Riley's Regency Reflections","description":"Research, Resources, & Book Store","inLanguage":"en-US","publisher":{"@id":"https:\/\/vanessariley.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/vanessariley.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMary Moore\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/vanessariley.com\/blog"},{"label":"Mary Moore","link":"https:\/\/vanessariley.com\/blog\/tag\/mary-moore\/"}],"_links":{"self":[{"href":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/tags\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vanessariley.com\/blog\/wp-json\/wp\/v2\/posts?tags=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}